{"id":479,"date":"2022-04-04T13:19:22","date_gmt":"2022-04-04T13:19:22","guid":{"rendered":"https:\/\/casinoreport.nl\/?p=479"},"modified":"2022-04-04T13:19:22","modified_gmt":"2022-04-04T13:19:22","slug":"luis-sinisterra-blijft-feyenoord-verbazen","status":"publish","type":"post","link":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/","title":{"rendered":"&#8216;Luis Sinisterra blijft Feyenoord verbazen&#8217;"},"content":{"rendered":"<h4>Luis Sinisterra speelt dit seizoen de pannen van het dak bij Feyenoord en was gisteren tegen Willem II ook weer uiterst belangrijk. Hij maakte namelijk de 1-0 in het met 2-2 gewonnen duel. Volgens De Telegraaf was Feyenoord blij dat Sinisterra uiteindelijk mee kon spelen tegen de Tilburgers.<\/h4>\n<p>&#8220;Met een uitverkocht huis en een redelijk frisse Luis Sinisterra in de aanval (laat teruggekeerd van twee interlands in Zuid-Amerika) leek dat niet de moeilijkste opdracht. Maar bijna zeventig minuten lang was het billenknijpen voor het Legioen \u00e9n voor Arne Slot op de bank van Feyenoord.&#8221;<\/p>\n<p>Uiteindelijk opende Sinisterra na ruim een uur spelen alsnog de score. De manier waarop de Colombiaan zich presenteerde, maakte indruk. Na een teleurstellende interlandperiode, waar in het Colombia niet lukte om een WK-ticket af te dwingen, schoot de buitenspeler zijn ploeg op voorsprong.<\/p>\n<p>Volgens De Telegraaf kan er daarom binnenkort een bloemetje richting Tilburg. &#8220;De vleugelspits maakte ondanks de mentale tik die hij kreeg door het missen van het WK met zijn nationale elftal, in De Kuip meteen weer een frisse indruk. In z\u2019n eentje forceerde hij in de 68e minuut de belangrijke 1-0 tegen de ploeg van Feyenoords vroegere technisch directeur Martin van Geel. Die laatste is de man die Sinisterra vastlegde voor Feyenoord en daar hebben de Rotterdammers tot op de dag van vandaag veel plezier van. Als Sinisterra straks ook nog eens een recordbedrag aan transfersom oplevert, kan daar best nog een bloemetje vanaf voor de \u2019td\u2019 die nu al weer even algemeen directeur is bij Willem II.&#8221;<\/p>\n<p>Sinisterra zou over belangstelling niet te klagen hebben. Voor hem persoonlijk was het WK aan het einde van dit jaar d\u00e9 mogelijkheid om zichzelf in de kijker te spelen bij een grote buitenlandse club. Wanneer de buitenspeler zijn niveau vast blijft houden en ook in de Conference League-confrontaties tegen Slavia Praag zijn ploeg bij de hand neemt, heeft hij misschien dat eindtoernooi niet eens nodig.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luis Sinisterra speelt dit seizoen de pannen van het dak bij Feyenoord en was gisteren tegen Willem II ook weer uiterst belangrijk. Hij maakte namelijk de 1-0 in het met 2-2 gewonnen duel. Volgens De Telegraaf was Feyenoord blij dat Sinisterra uiteindelijk mee kon spelen tegen de Tilburgers. &#8220;Met een uitverkocht huis en een redelijk [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voetbalnieuws"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#039;Luis Sinisterra blijft Feyenoord verbazen&#039; - Casinoreport<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;Luis Sinisterra blijft Feyenoord verbazen&#039; - Casinoreport\" \/>\n<meta property=\"og:description\" content=\"Luis Sinisterra speelt dit seizoen de pannen van het dak bij Feyenoord en was gisteren tegen Willem II ook weer uiterst belangrijk. Hij maakte namelijk de 1-0 in het met 2-2 gewonnen duel. Volgens De Telegraaf was Feyenoord blij dat Sinisterra uiteindelijk mee kon spelen tegen de Tilburgers. &#8220;Met een uitverkocht huis en een redelijk [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/\" \/>\n<meta property=\"og:site_name\" content=\"Casinoreport\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-04T13:19:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casinoreport.nl\/wp-content\/uploads\/2022\/04\/football-2698972_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"spenz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"spenz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/\"},\"author\":{\"name\":\"spenz\",\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/#\\\/schema\\\/person\\\/8e73e4b81f4162bfd55500f85ce20ee2\"},\"headline\":\"&#8216;Luis Sinisterra blijft Feyenoord verbazen&#8217;\",\"datePublished\":\"2022-04-04T13:19:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/\"},\"wordCount\":326,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casinoreport.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/football-2698972_1920.jpg\",\"articleSection\":[\"Voetbalnieuws\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/\",\"url\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/\",\"name\":\"'Luis Sinisterra blijft Feyenoord verbazen' - Casinoreport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casinoreport.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/football-2698972_1920.jpg\",\"datePublished\":\"2022-04-04T13:19:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/#\\\/schema\\\/person\\\/8e73e4b81f4162bfd55500f85ce20ee2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casinoreport.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/football-2698972_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/casinoreport.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/football-2698972_1920.jpg\",\"width\":1920,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/2022\\\/04\\\/04\\\/luis-sinisterra-blijft-feyenoord-verbazen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casinoreport.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;Luis Sinisterra blijft Feyenoord verbazen&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/#website\",\"url\":\"https:\\\/\\\/casinoreport.nl\\\/\",\"name\":\"Casinoreport\",\"description\":\"Online casino en gokken nieuwtjes selectief voor jou geselecteerd!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casinoreport.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casinoreport.nl\\\/#\\\/schema\\\/person\\\/8e73e4b81f4162bfd55500f85ce20ee2\",\"name\":\"spenz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g\",\"caption\":\"spenz\"},\"url\":\"https:\\\/\\\/casinoreport.nl\\\/index.php\\\/author\\\/spenz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"'Luis Sinisterra blijft Feyenoord verbazen' - Casinoreport","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/","og_locale":"nl_NL","og_type":"article","og_title":"'Luis Sinisterra blijft Feyenoord verbazen' - Casinoreport","og_description":"Luis Sinisterra speelt dit seizoen de pannen van het dak bij Feyenoord en was gisteren tegen Willem II ook weer uiterst belangrijk. Hij maakte namelijk de 1-0 in het met 2-2 gewonnen duel. Volgens De Telegraaf was Feyenoord blij dat Sinisterra uiteindelijk mee kon spelen tegen de Tilburgers. &#8220;Met een uitverkocht huis en een redelijk [&hellip;]","og_url":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/","og_site_name":"Casinoreport","article_published_time":"2022-04-04T13:19:22+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/casinoreport.nl\/wp-content\/uploads\/2022\/04\/football-2698972_1920.jpg","type":"image\/jpeg"}],"author":"spenz","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"spenz","Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/#article","isPartOf":{"@id":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/"},"author":{"name":"spenz","@id":"https:\/\/casinoreport.nl\/#\/schema\/person\/8e73e4b81f4162bfd55500f85ce20ee2"},"headline":"&#8216;Luis Sinisterra blijft Feyenoord verbazen&#8217;","datePublished":"2022-04-04T13:19:22+00:00","mainEntityOfPage":{"@id":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/"},"wordCount":326,"commentCount":0,"image":{"@id":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/#primaryimage"},"thumbnailUrl":"https:\/\/casinoreport.nl\/wp-content\/uploads\/2022\/04\/football-2698972_1920.jpg","articleSection":["Voetbalnieuws"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/","url":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/","name":"'Luis Sinisterra blijft Feyenoord verbazen' - Casinoreport","isPartOf":{"@id":"https:\/\/casinoreport.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/#primaryimage"},"image":{"@id":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/#primaryimage"},"thumbnailUrl":"https:\/\/casinoreport.nl\/wp-content\/uploads\/2022\/04\/football-2698972_1920.jpg","datePublished":"2022-04-04T13:19:22+00:00","author":{"@id":"https:\/\/casinoreport.nl\/#\/schema\/person\/8e73e4b81f4162bfd55500f85ce20ee2"},"breadcrumb":{"@id":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/#primaryimage","url":"https:\/\/casinoreport.nl\/wp-content\/uploads\/2022\/04\/football-2698972_1920.jpg","contentUrl":"https:\/\/casinoreport.nl\/wp-content\/uploads\/2022\/04\/football-2698972_1920.jpg","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/casinoreport.nl\/index.php\/2022\/04\/04\/luis-sinisterra-blijft-feyenoord-verbazen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casinoreport.nl\/"},{"@type":"ListItem","position":2,"name":"&#8216;Luis Sinisterra blijft Feyenoord verbazen&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/casinoreport.nl\/#website","url":"https:\/\/casinoreport.nl\/","name":"Casinoreport","description":"Online casino en gokken nieuwtjes selectief voor jou geselecteerd!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casinoreport.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/casinoreport.nl\/#\/schema\/person\/8e73e4b81f4162bfd55500f85ce20ee2","name":"spenz","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g","caption":"spenz"},"url":"https:\/\/casinoreport.nl\/index.php\/author\/spenz\/"}]}},"_links":{"self":[{"href":"https:\/\/casinoreport.nl\/index.php\/wp-json\/wp\/v2\/posts\/479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casinoreport.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casinoreport.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casinoreport.nl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casinoreport.nl\/index.php\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":-4,"href":"https:\/\/casinoreport.nl\/index.php\/wp-json\/wp\/v2\/posts\/479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casinoreport.nl\/index.php\/wp-json\/wp\/v2\/media\/470"}],"wp:attachment":[{"href":"https:\/\/casinoreport.nl\/index.php\/wp-json\/wp\/v2\/media?parent=479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casinoreport.nl\/index.php\/wp-json\/wp\/v2\/categories?post=479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casinoreport.nl\/index.php\/wp-json\/wp\/v2\/tags?post=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}